{"id":387,"date":"2019-06-07T16:50:03","date_gmt":"2019-06-07T16:50:03","guid":{"rendered":"http:\/\/dev.local.com\/?post_type=wpx-communities&#038;p=387"},"modified":"2025-11-26T19:17:53","modified_gmt":"2025-11-26T19:17:53","slug":"everett","status":"publish","type":"wpx-communities","link":"https:\/\/fkoafterschool.org\/zh\/communities-we-serve\/everett\/","title":{"rendered":"\u57c3\u5f17\u91cc\u7279"},"content":{"rendered":"<div class=\"whyy feature-wrap\">\n\n\n    \t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t<div class=\"feature verticenter-ib\" data-layout=\"image-left\">\n\t\t\t\t\n\t\t<div class=\"grid\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"grid__cell tablet__100 unit-5-12\">\n\t\t\t\t\t<figure class=\"fancy-border\">\n\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/fkoafterschool.org\/wp-content\/uploads\/2019\/09\/Deniece-Rodriguez.jpeg?resize=800%2C800&#038;ssl=1\" alt=\"Deniece Rodriguez\">\n\t\t\t\t\t<\/figure>\n\t\t\t\t<\/div>\t\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"grid__cell tablet__100 unit-6-12\">\n\n\t\t\t\t<div class=\"main-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pretitle\">\u5730\u533a\u603b\u76d1<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fkoafterschool.org\/zh\/team-members\/deniece-rodriguez\/\" target=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<h3>\u4e39\u59ae\u4e1d\u00b7\u53f2\u5bc6\u65af<\/h3>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<p>Deniece \u5728\u5317\u5cb8\u793e\u533a\u5b66\u9662\u5b8c\u6210\u4e86\u5e7c\u513f\u6559\u80b2\u8bfe\u7a0b\uff0c\u968f\u540e\u6bd5\u4e1a\u4e8e\u65af\u666e\u6797\u83f2\u5c14\u5fb7\u5b66\u9662\uff0c\u83b7\u5f97\u4e86\u7406\u5b66\u5b66\u58eb\u5b66\u4f4d\u3002\u5979\u4e8e 2007 \u5e74\u5f00\u59cb\u5728 FKO \u5de5\u4f5c\uff0c\u5e76\u83b7\u5f97\u4e86 EEC \u4e13\u5458\u9881\u53d1\u7684\u6770\u51fa\u6559\u5b66\u9886\u5bfc\u5956\u3002Deniece \u8ba4\u4e3a\u5979\u7684\u5b59\u5973\u4eec\u662f\u5979\u5728\u8be5\u9886\u57df\u5de5\u4f5c\u7684\u7075\u611f\u6765\u6e90\u3002\u5979\u4eec\u63d0\u9192\u5979\uff0c\u5b69\u5b50\u7684\u771f\u8bda\u662f\u6bcf\u4e2a\u4eba\u90fd\u53ef\u4ee5\u62e5\u6709\u7684\u771f\u6b63\u7684\u5feb\u4e50\u3002.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex-grid contact-links\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"cell\">\n\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t<a href=\"\/zh\/&\/#109;&#x61;&#105;&#x6c;t&#111;&#x3a;&#100;&#x72;o&#x64;r&#105;&#x67;&#117;&#x65;z&#x40;&#x66;&#107;&#x6f;a&#x66;t&#101;&#x72;&#115;&#x63;h&#x6f;o&#108;&#x2e;&#111;&#x72;g\" class=\"caps\" target=\"_blank\"><span class=\"icon icon-fko-email\"><\/span> <span class=\"text\">\u7535\u5b50\u90ae\u4ef6<\/span><\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"cell\">\n\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t<a href=\"tel:&#56;&#x35;&#55;&#x32;0&#x31;9&#57;&#x39;&#54;\" class=\"tel caps\" target=\"_blank\">\n\t<span class=\"phone-cell icon icon-fko-phone\"><\/span> \n\t<span class=\"phone-cell text-wrap\">\n\t\t<span class=\"text\">&#56;&#x35;7&#x32;&#x30;&#49;&#x39;9&#57;&#x36;<\/span> \t<\/span>\t\n<\/a>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"button\" href=\"https:\/\/fkoafterschool.org\/zh\/team-members\/deniece-rodriguez\/\" target=\"\">\u4e86\u89e3\u66f4\u591a<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\t\n\n\t\t\t<\/div>\t\n\n\t\t\t\n\t\t<\/div>\n\n\t<\/div>\n\n\t    \n    \n    \t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t<div class=\"feature verticenter-ib\" data-layout=\"image-right\">\n\t\t\t\t\n\t\t<div class=\"grid\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"grid__cell tablet__100 unit-6-12\">\n\n\t\t\t\t<div class=\"main-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\t\n\n\t\t\t<\/div>\t\n\n\t\t\t\n\t\t<\/div>\n\n\t<\/div>\n\n\t    \n    \n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"template":"","class_list":["post-387","wpx-communities","type-wpx-communities","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Everett - For Kids Only Afterschool<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fkoafterschool.org\/zh\/communities-we-serve\/everett\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Everett - For Kids Only Afterschool\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fkoafterschool.org\/zh\/communities-we-serve\/everett\/\" \/>\n<meta property=\"og:site_name\" content=\"For Kids Only Afterschool\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T19:17:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/everett\\\/\",\"url\":\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/everett\\\/\",\"name\":\"Everett - For Kids Only Afterschool\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/#website\"},\"datePublished\":\"2019-06-07T16:50:03+00:00\",\"dateModified\":\"2025-11-26T19:17:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/everett\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/everett\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/everett\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fkoafterschool.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Everett\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/#website\",\"url\":\"https:\\\/\\\/fkoafterschool.org\\\/\",\"name\":\"For Kids Only Afterschool\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fkoafterschool.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Everett - For Kids Only Afterschool","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fkoafterschool.org\/zh\/communities-we-serve\/everett\/","og_locale":"zh_CN","og_type":"article","og_title":"Everett - For Kids Only Afterschool","og_url":"https:\/\/fkoafterschool.org\/zh\/communities-we-serve\/everett\/","og_site_name":"For Kids Only Afterschool","article_modified_time":"2025-11-26T19:17:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fkoafterschool.org\/communities-we-serve\/everett\/","url":"https:\/\/fkoafterschool.org\/communities-we-serve\/everett\/","name":"Everett - For Kids Only Afterschool","isPartOf":{"@id":"https:\/\/fkoafterschool.org\/#website"},"datePublished":"2019-06-07T16:50:03+00:00","dateModified":"2025-11-26T19:17:53+00:00","breadcrumb":{"@id":"https:\/\/fkoafterschool.org\/communities-we-serve\/everett\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fkoafterschool.org\/communities-we-serve\/everett\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fkoafterschool.org\/communities-we-serve\/everett\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fkoafterschool.org\/"},{"@type":"ListItem","position":2,"name":"Everett"}]},{"@type":"WebSite","@id":"https:\/\/fkoafterschool.org\/#website","url":"https:\/\/fkoafterschool.org\/","name":"\u4ec5\u9650\u513f\u7ae5\u8bfe\u540e","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fkoafterschool.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fkoafterschool.org\/zh\/wp-json\/wp\/v2\/wpx-communities\/387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fkoafterschool.org\/zh\/wp-json\/wp\/v2\/wpx-communities"}],"about":[{"href":"https:\/\/fkoafterschool.org\/zh\/wp-json\/wp\/v2\/types\/wpx-communities"}],"version-history":[{"count":5,"href":"https:\/\/fkoafterschool.org\/zh\/wp-json\/wp\/v2\/wpx-communities\/387\/revisions"}],"predecessor-version":[{"id":12488,"href":"https:\/\/fkoafterschool.org\/zh\/wp-json\/wp\/v2\/wpx-communities\/387\/revisions\/12488"}],"wp:attachment":[{"href":"https:\/\/fkoafterschool.org\/zh\/wp-json\/wp\/v2\/media?parent=387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}