{"id":385,"date":"2019-06-07T16:49:51","date_gmt":"2019-06-07T16:49:51","guid":{"rendered":"http:\/\/dev.local.com\/?post_type=wpx-communities&#038;p=385"},"modified":"2025-09-30T15:38:33","modified_gmt":"2025-09-30T15:38:33","slug":"revere","status":"publish","type":"wpx-communities","link":"https:\/\/fkoafterschool.org\/pt_pt\/communities-we-serve\/revere\/","title":{"rendered":"Reverenciar"},"content":{"rendered":"<div class=\"whyy feature-wrap\">\n\n\n    \t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t<div class=\"feature verticenter-ib\" data-layout=\"image-left\">\n\t\t\t\t\n\t\t<div class=\"grid\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"grid__cell tablet__100 unit-5-12\">\n\t\t\t\t\t<figure class=\"fancy-border\">\n\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/fkoafterschool.org\/wp-content\/uploads\/2022\/12\/njb-scaled.jpeg?resize=800%2C800&#038;ssl=1\" alt=\"\">\n\t\t\t\t\t<\/figure>\n\t\t\t\t<\/div>\t\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"grid__cell tablet__100 unit-6-12\">\n\n\t\t\t\t<div class=\"main-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pretitle\">Diretor de Distrito<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fkoafterschool.org\/pt_pt\/team-members\/nick-jean-baptiste\/\" target=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<h3>Nick Jean Baptiste<\/h3>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<p>O Nick frequenta atualmente a escola de enfermagem e fisioterapia. Ele gosta de desportos e fitness, e trabalha no programa FKO desde 2015. Ele adora as parcerias que o FKO tem nas escolas e gosta de ver as crian\u00e7as a participar e a divertirem-se nos clubes de enriquecimento.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex-grid contact-links\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"cell\">\n\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t<a href=\"\/pt_pt\/&\/#x6d;a&#x69;&#108;&#x74;&#111;:&#x6e;j&#x65;&#97;&#x6e;&#98;a&#x70;&#116;&#x69;&#115;t&#x65;&#64;&#x66;&#107;&#x6f;&#97;f&#x74;e&#x72;&#115;&#x63;&#x68;o&#x6f;&#108;&#x2e;&#111;r&#x67;\" class=\"caps\" target=\"_blank\"><span class=\"icon icon-fko-email\"><\/span> <span class=\"text\">Correio eletr\u00f3nico<\/span><\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"cell\">\n\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t<a href=\"tel:&#56;&#x35;&#55;&#x32;&#48;&#x31;&#49;&#x30;&#56;&#x32;\" class=\"tel caps\" target=\"_blank\">\n\t<span class=\"phone-cell icon icon-fko-phone\"><\/span> \n\t<span class=\"phone-cell text-wrap\">\n\t\t<span class=\"text\">85720110&#56;&#50;<\/span> \t<\/span>\t\n<\/a>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"button\" href=\"https:\/\/fkoafterschool.org\/pt_pt\/team-members\/nick-jean-baptiste\/\" target=\"\">Saber Mais<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\t\n\n\t\t\t<\/div>\t\n\n\t\t\t\n\t\t<\/div>\n\n\t<\/div>\n\n\t    \n    \n    \t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t<div class=\"feature verticenter-ib\" data-layout=\"image-right\">\n\t\t\t\t\n\t\t<div class=\"grid\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"grid__cell tablet__100 unit-6-12\">\n\n\t\t\t\t<div class=\"main-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\t\n\n\t\t\t<\/div>\t\n\n\t\t\t\n\t\t<\/div>\n\n\t<\/div>\n\n\t    \n    \n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"template":"","class_list":["post-385","wpx-communities","type-wpx-communities","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Revere - For Kids Only Afterschool<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fkoafterschool.org\/pt_pt\/communities-we-serve\/revere\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revere - For Kids Only Afterschool\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fkoafterschool.org\/pt_pt\/communities-we-serve\/revere\/\" \/>\n<meta property=\"og:site_name\" content=\"For Kids Only Afterschool\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-30T15:38:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/revere\\\/\",\"url\":\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/revere\\\/\",\"name\":\"Revere - For Kids Only Afterschool\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/#website\"},\"datePublished\":\"2019-06-07T16:49:51+00:00\",\"dateModified\":\"2025-09-30T15:38:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/revere\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/revere\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/revere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fkoafterschool.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/#website\",\"url\":\"https:\\\/\\\/fkoafterschool.org\\\/\",\"name\":\"For Kids Only Afterschool\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fkoafterschool.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Revere - For Kids Only Afterschool","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fkoafterschool.org\/pt_pt\/communities-we-serve\/revere\/","og_locale":"pt_PT","og_type":"article","og_title":"Revere - For Kids Only Afterschool","og_url":"https:\/\/fkoafterschool.org\/pt_pt\/communities-we-serve\/revere\/","og_site_name":"For Kids Only Afterschool","article_modified_time":"2025-09-30T15:38:33+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fkoafterschool.org\/communities-we-serve\/revere\/","url":"https:\/\/fkoafterschool.org\/communities-we-serve\/revere\/","name":"Revere - For Kids Only Afterschool","isPartOf":{"@id":"https:\/\/fkoafterschool.org\/#website"},"datePublished":"2019-06-07T16:49:51+00:00","dateModified":"2025-09-30T15:38:33+00:00","breadcrumb":{"@id":"https:\/\/fkoafterschool.org\/communities-we-serve\/revere\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fkoafterschool.org\/communities-we-serve\/revere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fkoafterschool.org\/communities-we-serve\/revere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fkoafterschool.org\/"},{"@type":"ListItem","position":2,"name":"Revere"}]},{"@type":"WebSite","@id":"https:\/\/fkoafterschool.org\/#website","url":"https:\/\/fkoafterschool.org\/","name":"Apenas para Crian\u00e7as Depois da Escola","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fkoafterschool.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fkoafterschool.org\/pt_pt\/wp-json\/wp\/v2\/wpx-communities\/385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fkoafterschool.org\/pt_pt\/wp-json\/wp\/v2\/wpx-communities"}],"about":[{"href":"https:\/\/fkoafterschool.org\/pt_pt\/wp-json\/wp\/v2\/types\/wpx-communities"}],"version-history":[{"count":5,"href":"https:\/\/fkoafterschool.org\/pt_pt\/wp-json\/wp\/v2\/wpx-communities\/385\/revisions"}],"predecessor-version":[{"id":9474,"href":"https:\/\/fkoafterschool.org\/pt_pt\/wp-json\/wp\/v2\/wpx-communities\/385\/revisions\/9474"}],"wp:attachment":[{"href":"https:\/\/fkoafterschool.org\/pt_pt\/wp-json\/wp\/v2\/media?parent=385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}