{"id":383,"date":"2019-06-07T16:49:43","date_gmt":"2019-06-07T16:49:43","guid":{"rendered":"http:\/\/dev.local.com\/?post_type=wpx-communities&#038;p=383"},"modified":"2025-09-30T15:48:25","modified_gmt":"2025-09-30T15:48:25","slug":"chelsea","status":"publish","type":"wpx-communities","link":"https:\/\/fkoafterschool.org\/es\/communities-we-serve\/chelsea\/","title":{"rendered":"Chelsea"},"content":{"rendered":"<div class=\"whyy feature-wrap\">\n\n\n    \t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t<div class=\"feature verticenter-ib\" data-layout=\"image-left\">\n\t\t\t\t\n\t\t<div class=\"grid\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"grid__cell tablet__100 unit-5-12\">\n\t\t\t\t\t<figure class=\"fancy-border\">\n\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/fkoafterschool.org\/wp-content\/uploads\/2019\/09\/Patrick-Shea.jpeg?resize=800%2C800&#038;ssl=1\" alt=\"Patrick Shea\">\n\t\t\t\t\t<\/figure>\n\t\t\t\t<\/div>\t\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"grid__cell tablet__100 unit-6-12\">\n\n\t\t\t\t<div class=\"main-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pretitle\">Director de Distrito<\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fkoafterschool.org\/es\/team-members\/patrick-shea\/\" target=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<h3>Patrick Shea<\/h3>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<p>Patrick se gradu\u00f3 de Salem State University con su Licenciatura en Biolog\u00eda. Se dio cuenta de que disfrutaba cada momento trabajando en programas extraescolares desde que comenz\u00f3 en 2016. Este es definitivamente el camino para Patrick, y tener la oportunidad de alegrar el d\u00eda de un ni\u00f1o es la raz\u00f3n por la que viene a trabajar.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"flex-grid contact-links\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"cell\">\n\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t<a href=\"\/es\/&\/#109;&#x61;&#105;&#x6c;&#116;&#x6f;:&#x70;s&#x68;e&#97;&#x40;&#102;&#x6b;&#111;&#x61;&#102;&#x74;e&#x72;s&#x63;h&#111;&#x6f;&#108;&#x2e;&#111;&#x72;&#103;\" class=\"caps\" target=\"_blank\"><span class=\"icon icon-fko-email\"><\/span> <span class=\"text\">Correo electr\u00f3nico<\/span><\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"cell\">\n\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t<a href=\"tel:&#x33;&#x35;&#x31;&#x32;&#x33;&#x37;&#x32;&#x39;&#x36;&#x32;\" class=\"tel caps\" target=\"_blank\">\n\t<span class=\"phone-cell icon icon-fko-phone\"><\/span> \n\t<span class=\"phone-cell text-wrap\">\n\t\t<span class=\"text\">&#x33;5&#x31;2&#x33;&#55;&#x32;&#57;6&#x32;<\/span> \t<\/span>\t\n<\/a>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"button\" href=\"https:\/\/fkoafterschool.org\/es\/team-members\/patrick-shea\/\" target=\"\">Aprende m\u00e1s<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\t\n\n\t\t\t<\/div>\t\n\n\t\t\t\n\t\t<\/div>\n\n\t<\/div>\n\n\t    \n    \n    \t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\n\t<div class=\"feature verticenter-ib\" data-layout=\"image-right\">\n\t\t\t\t\n\t\t<div class=\"grid\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"grid__cell tablet__100 unit-6-12\">\n\n\t\t\t\t<div class=\"main-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\t\n\n\t\t\t<\/div>\t\n\n\t\t\t\n\t\t<\/div>\n\n\t<\/div>\n\n\t    \n    \n<\/div>\n\n\n<p class=\"\"><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"template":"","class_list":["post-383","wpx-communities","type-wpx-communities","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chelsea - For Kids Only Afterschool<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fkoafterschool.org\/es\/communities-we-serve\/chelsea\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chelsea - For Kids Only Afterschool\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fkoafterschool.org\/es\/communities-we-serve\/chelsea\/\" \/>\n<meta property=\"og:site_name\" content=\"For Kids Only Afterschool\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-30T15:48:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/chelsea\\\/\",\"url\":\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/chelsea\\\/\",\"name\":\"Chelsea - For Kids Only Afterschool\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/#website\"},\"datePublished\":\"2019-06-07T16:49:43+00:00\",\"dateModified\":\"2025-09-30T15:48:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/chelsea\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/chelsea\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/communities-we-serve\\\/chelsea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fkoafterschool.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chelsea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fkoafterschool.org\\\/#website\",\"url\":\"https:\\\/\\\/fkoafterschool.org\\\/\",\"name\":\"For Kids Only Afterschool\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fkoafterschool.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chelsea - For Kids Only Afterschool","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fkoafterschool.org\/es\/communities-we-serve\/chelsea\/","og_locale":"es_MX","og_type":"article","og_title":"Chelsea - For Kids Only Afterschool","og_url":"https:\/\/fkoafterschool.org\/es\/communities-we-serve\/chelsea\/","og_site_name":"For Kids Only Afterschool","article_modified_time":"2025-09-30T15:48:25+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fkoafterschool.org\/communities-we-serve\/chelsea\/","url":"https:\/\/fkoafterschool.org\/communities-we-serve\/chelsea\/","name":"Chelsea - For Kids Only Afterschool","isPartOf":{"@id":"https:\/\/fkoafterschool.org\/#website"},"datePublished":"2019-06-07T16:49:43+00:00","dateModified":"2025-09-30T15:48:25+00:00","breadcrumb":{"@id":"https:\/\/fkoafterschool.org\/communities-we-serve\/chelsea\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fkoafterschool.org\/communities-we-serve\/chelsea\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fkoafterschool.org\/communities-we-serve\/chelsea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fkoafterschool.org\/"},{"@type":"ListItem","position":2,"name":"Chelsea"}]},{"@type":"WebSite","@id":"https:\/\/fkoafterschool.org\/#website","url":"https:\/\/fkoafterschool.org\/","name":"Solo para Ni\u00f1os Despu\u00e9s de la Escuela","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fkoafterschool.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fkoafterschool.org\/es\/wp-json\/wp\/v2\/wpx-communities\/383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fkoafterschool.org\/es\/wp-json\/wp\/v2\/wpx-communities"}],"about":[{"href":"https:\/\/fkoafterschool.org\/es\/wp-json\/wp\/v2\/types\/wpx-communities"}],"version-history":[{"count":5,"href":"https:\/\/fkoafterschool.org\/es\/wp-json\/wp\/v2\/wpx-communities\/383\/revisions"}],"predecessor-version":[{"id":12489,"href":"https:\/\/fkoafterschool.org\/es\/wp-json\/wp\/v2\/wpx-communities\/383\/revisions\/12489"}],"wp:attachment":[{"href":"https:\/\/fkoafterschool.org\/es\/wp-json\/wp\/v2\/media?parent=383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}